{"id":2800,"count":5,"description":"","link":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/","name":"V\u00f5rgud","slug":"vorgud","taxonomy":"product_cat","parent":2798,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00f5rgud - Espak E-pood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00f5rgud - Espak E-pood\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/\" \/>\n<meta property=\"og:site_name\" content=\"Espak E-pood\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/\",\"url\":\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/\",\"name\":\"V\u00f5rgud - Espak E-pood\",\"isPartOf\":{\"@id\":\"https:\/\/espak.ee\/epood\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/#breadcrumb\"},\"inLanguage\":\"et\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/espak.ee\/epood\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcLDEHITUS\",\"item\":\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fassaadimaterjalid\",\"item\":\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Fassaadi lisatarvikud\",\"item\":\"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"V\u00f5rgud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/espak.ee\/epood\/#website\",\"url\":\"https:\/\/espak.ee\/epood\/\",\"name\":\"Espak E-pood\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/espak.ee\/epood\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00f5rgud - Espak E-pood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/","og_locale":"et_EE","og_type":"article","og_title":"V\u00f5rgud - Espak E-pood","og_url":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/","og_site_name":"Espak E-pood","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/","url":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/","name":"V\u00f5rgud - Espak E-pood","isPartOf":{"@id":"https:\/\/espak.ee\/epood\/#website"},"breadcrumb":{"@id":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/#breadcrumb"},"inLanguage":"et"},{"@type":"BreadcrumbList","@id":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/vorgud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/espak.ee\/epood\/"},{"@type":"ListItem","position":2,"name":"\u00dcLDEHITUS","item":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/"},{"@type":"ListItem","position":3,"name":"Fassaadimaterjalid","item":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/"},{"@type":"ListItem","position":4,"name":"Fassaadi lisatarvikud","item":"https:\/\/espak.ee\/epood\/tootekategooria\/uldehitus\/fassaadimaterjalid\/fassaadi-lisatarvikud\/"},{"@type":"ListItem","position":5,"name":"V\u00f5rgud"}]},{"@type":"WebSite","@id":"https:\/\/espak.ee\/epood\/#website","url":"https:\/\/espak.ee\/epood\/","name":"Espak E-pood","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espak.ee\/epood\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"}]}},"_links":{"self":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_cat\/2800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_cat\/2798"}],"wp:post_type":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product?product_cat=2800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}