{"id":96536,"date":"2021-10-06T23:13:21","date_gmt":"2021-10-06T23:13:21","guid":{"rendered":"https:\/\/espak.ee\/epood\/?post_type=product&#038;p=96536"},"modified":"2026-01-20T09:14:42","modified_gmt":"2026-01-20T07:14:42","slug":"kaablihoidik-6-20mm-10tk-kah620h-10","status":"publish","type":"product","link":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/","title":{"rendered":"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10"},"content":{"rendered":"<div class=\"row\"  id=\"row-2083550821\">\n\n\t<div id=\"col-144207566\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Kaablihoidik hall 6-20 mm 10tk\/pk<\/h3>\n\t<div id=\"gap-1043603688\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1043603688 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-745150784\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-742828009\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-742828009 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" ><\/div>\n<p><strong>\u00dcksikasjalikuma n\u00f5u saamiseks v\u00f5tke \u00fchendust:<br \/><\/strong>INSTABALT EESTI<br \/>Kadaka tee 52d<br \/>12915<br \/>Tallinn<br \/>+372 4896544<\/p>\n<div class=\"is-divider divider clearfix\" ><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":96700,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2935,2934,2936,4181],"product_tag":[],"class_list":{"0":"post-96536","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-elektrikaubad","7":"product_cat-elektrikaubad-ja-valgustid","8":"product_cat-installatsioon","9":"product_cat-kaabliklambrid","10":"pa_kaubamark-instabalt-eesti-ou","12":"first","13":"outofstock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KAABLIHOIDIK 6-20MM 10TK KAH620H\/10 - Espak E-pood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10 - Espak E-pood\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Espak E-pood\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T07:14:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/\",\"url\":\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/\",\"name\":\"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10 - Espak E-pood\",\"isPartOf\":{\"@id\":\"https:\/\/espak.ee\/epood\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg\",\"datePublished\":\"2021-10-06T23:13:21+00:00\",\"dateModified\":\"2026-01-20T07:14:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#primaryimage\",\"url\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg\",\"contentUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/espak.ee\/epood\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tootevalik\",\"item\":\"https:\/\/espak.ee\/epood\/tootevalik\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/espak.ee\/epood\/#website\",\"url\":\"https:\/\/espak.ee\/epood\/\",\"name\":\"Espak E-pood\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/espak.ee\/epood\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10 - Espak E-pood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/","og_locale":"et_EE","og_type":"article","og_title":"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10 - Espak E-pood","og_url":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/","og_site_name":"Espak E-pood","article_modified_time":"2026-01-20T07:14:42+00:00","og_image":[{"width":2048,"height":2048,"url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/","url":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/","name":"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10 - Espak E-pood","isPartOf":{"@id":"https:\/\/espak.ee\/epood\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#primaryimage"},"image":{"@id":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#primaryimage"},"thumbnailUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg","datePublished":"2021-10-06T23:13:21+00:00","dateModified":"2026-01-20T07:14:42+00:00","breadcrumb":{"@id":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#primaryimage","url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg","contentUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2021\/10\/4751002312436_a-scaled.jpg","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/espak.ee\/epood\/toode\/kaablihoidik-6-20mm-10tk-kah620h-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/espak.ee\/epood\/"},{"@type":"ListItem","position":2,"name":"Tootevalik","item":"https:\/\/espak.ee\/epood\/tootevalik\/"},{"@type":"ListItem","position":3,"name":"KAABLIHOIDIK 6-20MM 10TK KAH620H\/10"}]},{"@type":"WebSite","@id":"https:\/\/espak.ee\/epood\/#website","url":"https:\/\/espak.ee\/epood\/","name":"Espak E-pood","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espak.ee\/epood\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"}]}},"_links":{"self":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product\/96536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/comments?post=96536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media\/96700"}],"wp:attachment":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media?parent=96536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_brand?post=96536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_cat?post=96536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_tag?post=96536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}