{"id":41265,"date":"2020-09-15T07:06:22","date_gmt":"2020-09-15T04:06:22","guid":{"rendered":"https:\/\/espak.ee\/hinnakiri\/?post_type=product&#038;p=41265"},"modified":"2025-05-12T22:21:13","modified_gmt":"2025-05-12T19:21:13","slug":"fibo-sillus-1001790","status":"publish","type":"product","link":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/","title":{"rendered":"FIBO SILLUS 100*1790"},"content":{"rendered":"<div class=\"row\"  id=\"row-1420016513\">\n\n\t<div id=\"col-1066953359\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>100 mm paksune sillus kuni 1500 mm laiuste avade sildamiseks.<\/p>\n<div class=\"message-box relative\" style=\"padding-top:15px;padding-bottom:15px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" ><\/div><div class=\"container relative\"><div class=\"inner last-reset\"><div class=\"row align-middle align-center\"  id=\"row-476395242\">\n\t<div id=\"col-32485104\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t<div class=\"row\"  id=\"row-2109034886\">\n\t<div id=\"col-1158525406\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><i class=\"fa fa-check fa-2x\"><\/i> <strong>Kerge<\/strong><\/p>\n<p><i class=\"fa fa-check fa-2x\"><\/i> <strong>Lihtne paigaldada<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1158525406 > .col-inner {\n  margin: 10px 0px 15px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\t<div id=\"col-1379435227\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><i class=\"fa fa-check fa-2x\"><\/i> <strong>Tulekindel<\/strong><\/p>\n<p><i class=\"fa fa-check fa-2x\"><\/i> <strong>K\u00fclmakindel<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1379435227 > .col-inner {\n  margin: 10px 0px 15px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t<\/div>\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t<\/div><\/div><\/div><\/div>\t<div id=\"gap-1386198270\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1386198270 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<p><strong>Kasutamine:<\/strong> Avade sildamine<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1327353430\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong>\u00dcksikasjalikuma n\u00f5u saamiseks v\u00f5tke \u00fchendust:<br \/><\/strong>SAINT-GOBAIN EESTI AS, Peterburi tee 75, 11415 Tallinn, Telefon: +372 6209 510<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":67225,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[3203,3204,3206,2697],"product_tag":[],"class_list":{"0":"post-41265","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-muurimaterjalid","7":"product_cat-plokid-ja-sillused","8":"product_cat-sillused","9":"product_cat-uldehitus","10":"pa_kaubamark-saint-gobain-ehitustooted-as","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FIBO SILLUS 100*1790 - Espak E-pood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIBO SILLUS 100*1790 - Espak E-pood\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/\" \/>\n<meta property=\"og:site_name\" content=\"Espak E-pood\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-12T19:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/\",\"url\":\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/\",\"name\":\"FIBO SILLUS 100*1790 - Espak E-pood\",\"isPartOf\":{\"@id\":\"https:\/\/espak.ee\/epood\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg\",\"datePublished\":\"2020-09-15T04:06:22+00:00\",\"dateModified\":\"2025-05-12T19:21:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#primaryimage\",\"url\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg\",\"contentUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg\",\"width\":1920,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/espak.ee\/epood\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tootevalik\",\"item\":\"https:\/\/espak.ee\/epood\/tootevalik\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FIBO SILLUS 100*1790\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/espak.ee\/epood\/#website\",\"url\":\"https:\/\/espak.ee\/epood\/\",\"name\":\"Espak E-pood\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/espak.ee\/epood\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIBO SILLUS 100*1790 - Espak E-pood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/","og_locale":"et_EE","og_type":"article","og_title":"FIBO SILLUS 100*1790 - Espak E-pood","og_url":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/","og_site_name":"Espak E-pood","article_modified_time":"2025-05-12T19:21:13+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/","url":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/","name":"FIBO SILLUS 100*1790 - Espak E-pood","isPartOf":{"@id":"https:\/\/espak.ee\/epood\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#primaryimage"},"image":{"@id":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#primaryimage"},"thumbnailUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg","datePublished":"2020-09-15T04:06:22+00:00","dateModified":"2025-05-12T19:21:13+00:00","breadcrumb":{"@id":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#primaryimage","url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg","contentUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/1000322.jpg","width":1920,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/espak.ee\/epood\/toode\/fibo-sillus-1001790\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/espak.ee\/epood\/"},{"@type":"ListItem","position":2,"name":"Tootevalik","item":"https:\/\/espak.ee\/epood\/tootevalik\/"},{"@type":"ListItem","position":3,"name":"FIBO SILLUS 100*1790"}]},{"@type":"WebSite","@id":"https:\/\/espak.ee\/epood\/#website","url":"https:\/\/espak.ee\/epood\/","name":"Espak E-pood","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espak.ee\/epood\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"}]}},"_links":{"self":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product\/41265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/comments?post=41265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media\/67225"}],"wp:attachment":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media?parent=41265"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_brand?post=41265"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_cat?post=41265"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_tag?post=41265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}