{"id":123215,"date":"2022-06-15T06:00:57","date_gmt":"2022-06-15T06:00:57","guid":{"rendered":"https:\/\/espak.ee\/epood\/?post_type=product&#038;p=123215"},"modified":"2024-03-23T03:12:31","modified_gmt":"2024-03-23T01:12:31","slug":"bassein-d30576cm-bestway","status":"publish","type":"product","link":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/","title":{"rendered":"BASSEIN D305*76CM BESTWAY"},"content":{"rendered":"<div class=\"row\"  id=\"row-1209793302\">\n\n\t<div id=\"col-538493249\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Bassein 305x76cm filterpumbaga Bestway<\/h3>\n<p>Lihtsasti \u00fcles seatav bassein.<br \/>\nPuhuge basseini \u00fclemine \u00e4\u00e4r \u00f5hku t\u00e4is ja hakake veega t\u00e4itma, bassein v\u00f5tab \u00f5ige kuju veega t\u00e4itudes.<br \/>\nVeehulk: 3800L.<br \/>\nT\u00fchjendusventiil vee v\u00e4lja laskmiseks.<br \/>\nKaasas paranduslapp, filterpump ja filtrikassett.<br \/>\nMitte j\u00e4tta lapsi basseini j\u00e4relvalveta!<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1630158852\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"is-divider divider clearfix\" ><\/div>\n<p><strong>\u00dcksikasjalikuma n\u00f5u saamiseks v\u00f5tke \u00fchendust:<br \/><\/strong>Espak AS<br \/>Viadukti 42<br \/>11313<br \/>Tallinn<br \/>+372 6 512333<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":125054,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2788,3597,3598,3599],"product_tag":[],"class_list":{"0":"post-123215","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aiatarbed-ja-kodukaubad","7":"product_cat-spordikaubad","8":"product_cat-spordikaubad-spordikaubad","9":"product_cat-spordikaubad-spordikaubad-spordikaubad","10":"pa_kaubamark-edco-eindhoven-bv","12":"first","13":"outofstock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BASSEIN D305*76CM BESTWAY - Espak E-pood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BASSEIN D305*76CM BESTWAY - Espak E-pood\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/\" \/>\n<meta property=\"og:site_name\" content=\"Espak E-pood\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-23T01:12:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/\",\"url\":\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/\",\"name\":\"BASSEIN D305*76CM BESTWAY - Espak E-pood\",\"isPartOf\":{\"@id\":\"https:\/\/espak.ee\/epood\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg\",\"datePublished\":\"2022-06-15T06:00:57+00:00\",\"dateModified\":\"2024-03-23T01:12:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#primaryimage\",\"url\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg\",\"contentUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/espak.ee\/epood\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tootevalik\",\"item\":\"https:\/\/espak.ee\/epood\/tootevalik\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BASSEIN D305*76CM BESTWAY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/espak.ee\/epood\/#website\",\"url\":\"https:\/\/espak.ee\/epood\/\",\"name\":\"Espak E-pood\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/espak.ee\/epood\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BASSEIN D305*76CM BESTWAY - Espak E-pood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/","og_locale":"et_EE","og_type":"article","og_title":"BASSEIN D305*76CM BESTWAY - Espak E-pood","og_url":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/","og_site_name":"Espak E-pood","article_modified_time":"2024-03-23T01:12:31+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/","url":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/","name":"BASSEIN D305*76CM BESTWAY - Espak E-pood","isPartOf":{"@id":"https:\/\/espak.ee\/epood\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#primaryimage"},"image":{"@id":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#primaryimage"},"thumbnailUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg","datePublished":"2022-06-15T06:00:57+00:00","dateModified":"2024-03-23T01:12:31+00:00","breadcrumb":{"@id":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#primaryimage","url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg","contentUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/06\/694213895129_ss-1_preview.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/espak.ee\/epood\/toode\/bassein-d30576cm-bestway\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/espak.ee\/epood\/"},{"@type":"ListItem","position":2,"name":"Tootevalik","item":"https:\/\/espak.ee\/epood\/tootevalik\/"},{"@type":"ListItem","position":3,"name":"BASSEIN D305*76CM BESTWAY"}]},{"@type":"WebSite","@id":"https:\/\/espak.ee\/epood\/#website","url":"https:\/\/espak.ee\/epood\/","name":"Espak E-pood","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espak.ee\/epood\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"}]}},"_links":{"self":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product\/123215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/comments?post=123215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media\/125054"}],"wp:attachment":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media?parent=123215"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_brand?post=123215"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_cat?post=123215"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_tag?post=123215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}