{"id":119492,"date":"2022-05-19T05:45:13","date_gmt":"2022-05-19T05:45:13","guid":{"rendered":"https:\/\/espak.ee\/epood\/?post_type=product&#038;p=119492"},"modified":"2024-03-23T03:41:36","modified_gmt":"2024-03-23T01:41:36","slug":"uhendusklambrid-einhell-4tk-pk","status":"publish","type":"product","link":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/","title":{"rendered":"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK"},"content":{"rendered":"<div class=\"row\"  id=\"row-1989533919\">\n\n\t<div id=\"col-711265733\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>\u00dchendusklambrid Einhell 4tk\/pk<\/h3>\n<p>\u00dchendusklambrid piirdekaabli \u00fchendusteks Einhelli robotmuruniidukitele. <\/p>\n\t<div id=\"gap-1597386741\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1597386741 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-376726562\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"is-divider divider clearfix\" ><\/div>\n<p><strong>\u00dcksikasjalikuma n\u00f5u saamiseks v\u00f5tke \u00fchendust:<br \/><\/strong>Espak AS<br \/>Viadukti 42<br \/>11313<br \/>Tallinn<br \/> T\u00f6\u00f6riista osakond +372 6512 335<br \/><a href=\"mailto:tooriist@espak.ee\">tooriist@espak.ee<\/a><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":125443,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2789,2788,2790,3355],"product_tag":[],"class_list":{"0":"post-119492","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aiatarbed","7":"product_cat-aiatarbed-ja-kodukaubad","8":"product_cat-aiatehnika","9":"product_cat-aiatehnika-tarvikud","10":"pa_kaubamark-einhell-germany-ag","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK - Espak E-pood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK - Espak E-pood\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/\" \/>\n<meta property=\"og:site_name\" content=\"Espak E-pood\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-23T01:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/\",\"url\":\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/\",\"name\":\"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK - Espak E-pood\",\"isPartOf\":{\"@id\":\"https:\/\/espak.ee\/epood\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg\",\"datePublished\":\"2022-05-19T05:45:13+00:00\",\"dateModified\":\"2024-03-23T01:41:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#primaryimage\",\"url\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg\",\"contentUrl\":\"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/espak.ee\/epood\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tootevalik\",\"item\":\"https:\/\/espak.ee\/epood\/tootevalik\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/espak.ee\/epood\/#website\",\"url\":\"https:\/\/espak.ee\/epood\/\",\"name\":\"Espak E-pood\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/espak.ee\/epood\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK - Espak E-pood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/","og_locale":"et_EE","og_type":"article","og_title":"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK - Espak E-pood","og_url":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/","og_site_name":"Espak E-pood","article_modified_time":"2024-03-23T01:41:36+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/","url":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/","name":"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK - Espak E-pood","isPartOf":{"@id":"https:\/\/espak.ee\/epood\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#primaryimage"},"image":{"@id":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#primaryimage"},"thumbnailUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg","datePublished":"2022-05-19T05:45:13+00:00","dateModified":"2024-03-23T01:41:36+00:00","breadcrumb":{"@id":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#primaryimage","url":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg","contentUrl":"https:\/\/espak.ee\/epood\/wp-content\/uploads\/2022\/05\/3414022_11019_001_Verbindungsklemmen_Pic-2.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/espak.ee\/epood\/toode\/uhendusklambrid-einhell-4tk-pk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/espak.ee\/epood\/"},{"@type":"ListItem","position":2,"name":"Tootevalik","item":"https:\/\/espak.ee\/epood\/tootevalik\/"},{"@type":"ListItem","position":3,"name":"\u00dcHENDUSKLAMBRID EINHELL 4TK\/PK"}]},{"@type":"WebSite","@id":"https:\/\/espak.ee\/epood\/#website","url":"https:\/\/espak.ee\/epood\/","name":"Espak E-pood","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espak.ee\/epood\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"}]}},"_links":{"self":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product\/119492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/comments?post=119492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media\/125443"}],"wp:attachment":[{"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/media?parent=119492"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_brand?post=119492"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_cat?post=119492"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/espak.ee\/epood\/wp-json\/wp\/v2\/product_tag?post=119492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}